{"id":21548,"date":"2025-11-27T09:39:51","date_gmt":"2025-11-27T07:39:51","guid":{"rendered":"https:\/\/www.noa.gr\/dye\/"},"modified":"2026-02-23T15:27:03","modified_gmt":"2026-02-23T13:27:03","slug":"dye","status":"publish","type":"page","link":"https:\/\/www.noa.gr\/en\/dye\/","title":{"rendered":"Research Support Directorate (RSD)"},"content":{"rendered":"<p>\u00a0<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a0<\/p>\n","protected":false},"author":11,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page_template\/page-sundesmoi.php","meta":{"footnotes":"","_members_access_role":[],"_members_access_error":""},"class_list":["post-21548","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Research Support Directorate (RSD) - National Observatory of Athens<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.noa.gr\/en\/dye\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Research Support Directorate (RSD) - National Observatory of Athens\" \/>\n<meta property=\"og:description\" content=\"\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.noa.gr\/en\/dye\/\" \/>\n<meta property=\"og:site_name\" content=\"National Observatory of Athens\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-23T13:27:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/dye\\\/\",\"url\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/dye\\\/\",\"name\":\"Research Support Directorate (RSD) - National Observatory of Athens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/#website\"},\"datePublished\":\"2025-11-27T07:39:51+00:00\",\"dateModified\":\"2026-02-23T13:27:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/dye\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.noa.gr\\\/en\\\/dye\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/dye\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Research Support Directorate (RSD)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/\",\"name\":\"National Observatory of Athens\",\"description\":\"175+ of service to research and society\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.noa.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Research Support Directorate (RSD) - National Observatory of Athens","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.noa.gr\/en\/dye\/","og_locale":"en_US","og_type":"article","og_title":"Research Support Directorate (RSD) - National Observatory of Athens","og_description":"\u00a0","og_url":"https:\/\/www.noa.gr\/en\/dye\/","og_site_name":"National Observatory of Athens","article_modified_time":"2026-02-23T13:27:03+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.noa.gr\/en\/dye\/","url":"https:\/\/www.noa.gr\/en\/dye\/","name":"Research Support Directorate (RSD) - National Observatory of Athens","isPartOf":{"@id":"https:\/\/www.noa.gr\/en\/#website"},"datePublished":"2025-11-27T07:39:51+00:00","dateModified":"2026-02-23T13:27:03+00:00","breadcrumb":{"@id":"https:\/\/www.noa.gr\/en\/dye\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.noa.gr\/en\/dye\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.noa.gr\/en\/dye\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.noa.gr\/en\/"},{"@type":"ListItem","position":2,"name":"Research Support Directorate (RSD)"}]},{"@type":"WebSite","@id":"https:\/\/www.noa.gr\/en\/#website","url":"https:\/\/www.noa.gr\/en\/","name":"National Observatory of Athens","description":"175+ of service to research and society","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.noa.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.noa.gr\/en\/wp-json\/wp\/v2\/pages\/21548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.noa.gr\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.noa.gr\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.noa.gr\/en\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/www.noa.gr\/en\/wp-json\/wp\/v2\/comments?post=21548"}],"version-history":[{"count":4,"href":"https:\/\/www.noa.gr\/en\/wp-json\/wp\/v2\/pages\/21548\/revisions"}],"predecessor-version":[{"id":21632,"href":"https:\/\/www.noa.gr\/en\/wp-json\/wp\/v2\/pages\/21548\/revisions\/21632"}],"wp:attachment":[{"href":"https:\/\/www.noa.gr\/en\/wp-json\/wp\/v2\/media?parent=21548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}